{"id":78,"date":"2017-06-08T15:53:49","date_gmt":"2017-06-08T15:53:49","guid":{"rendered":"http:\/\/ddthemesdemo.com\/charlotte-blog\/?p=78"},"modified":"2023-05-06T15:52:16","modified_gmt":"2023-05-06T19:52:16","slug":"see-celebrities-in-the-vanity-fair-coachella-portrait-studio","status":"publish","type":"post","link":"https:\/\/iacodvzla.com\/index.php\/2017\/06\/08\/see-celebrities-in-the-vanity-fair-coachella-portrait-studio\/","title":{"rendered":"Paneles de madera para ambientes hermosos"},"content":{"rendered":"<p>Como ya sabemos las modas vuelven y no solo en el mundo textil, en el \u00e1mbito del interiorismo y la decoraci\u00f3n ocurre lo mismo y podemos toparnos con tendencias de dise\u00f1o que fueron un \u00e9xito hace d\u00e9cadas y que hoy en d\u00eda vuelven a estar en su punto m\u00e1s \u00e1lgido.<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-large wp-image-1841\" src=\"https:\/\/iacodvzla.com\/wp-content\/uploads\/2017\/06\/Paneles-de-madera-wall-panel-caracas-iacod-1024x614.jpg\" alt=\"\" width=\"1024\" height=\"614\" srcset=\"https:\/\/iacodvzla.com\/wp-content\/uploads\/2017\/06\/Paneles-de-madera-wall-panel-caracas-iacod-1024x614.jpg 1024w, https:\/\/iacodvzla.com\/wp-content\/uploads\/2017\/06\/Paneles-de-madera-wall-panel-caracas-iacod-300x180.jpg 300w, https:\/\/iacodvzla.com\/wp-content\/uploads\/2017\/06\/Paneles-de-madera-wall-panel-caracas-iacod-768x461.jpg 768w, https:\/\/iacodvzla.com\/wp-content\/uploads\/2017\/06\/Paneles-de-madera-wall-panel-caracas-iacod-1536x922.jpg 1536w, https:\/\/iacodvzla.com\/wp-content\/uploads\/2017\/06\/Paneles-de-madera-wall-panel-caracas-iacod-2048x1229.jpg 2048w, https:\/\/iacodvzla.com\/wp-content\/uploads\/2017\/06\/Paneles-de-madera-wall-panel-caracas-iacod-1320x792.jpg 1320w, https:\/\/iacodvzla.com\/wp-content\/uploads\/2017\/06\/Paneles-de-madera-wall-panel-caracas-iacod-495x297.jpg 495w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Es el caso de la madera. Es verdad que el recurso de este material natural tan noble lleva tiempo siendo tendencia en todas sus variantes y formas, y cada vez somos m\u00e1s los que apostamos por este tipo de materiales que nos producen sensaci\u00f3n de calidez, confianza y autenticidad. La madera se usa principalmente para revestir nuestros suelos, pero hoy venimos a contaros soluciones verticales, no solo existe la pintura, el alicatado o los papeles pintados para decorar nuestras paredes, tambi\u00e9n podemos recurrir a los\u00a0<strong>revestimientos de madera<\/strong>.<\/p>\n<p>Esta tendencia apareci\u00f3 en los a\u00f1os 60 y 70 y se utilizaba como decoraci\u00f3n sobre paredes en viviendas, aportando calidez y personalidad a diferentes estancias como pod\u00eda ser la sala de estar o despacho. En varias ocasiones no se trataba de madera maciza, sino que se empleaba un aglomerado, dejando la parte visible de madera que era normalmente en tonos oscuros y barnizada. Este dise\u00f1o aportaba elegancia y sobriedad a la par que aislamiento ac\u00fastico.<\/p>\n<p>Hoy en d\u00eda, recuperamos esta tendencia en\u00a0<strong>tipos de madera m\u00e1s claros<\/strong>\u00a0y acabados mate que nos proporcionen calidez en estancias y no nos quitan\u00a0<strong>luminosidad<\/strong>. Jugamos con la combinaci\u00f3n de diferentes tipos de madera, cortes, formas y disposiciones que nos proporcionan un juego visual, interesante y ante todo original.<\/p>\n<blockquote class=\"right\"><p><cite>&#8220;La casa debe ser el estuche de la vida, la m\u00e1quina de felicidad&#8221;.<strong>Le Corbusier.<\/strong><\/cite><\/p><\/blockquote>\n<h2><strong>\u00bfQu\u00e9 madera escoger?<\/strong><\/h2>\n<p>Existen diferentes tipos de madera que podemos clasificar en duras o blandas. Las maderas duras provienen de \u00e1rboles de un largo per\u00edodo de crecimiento, lo que las hace tambi\u00e9n m\u00e1s caras como puede ser el Roble, el Haya, la Caoba, el Olmo, el Olivo o el Nogal. Son ideales para el uso exterior, ya que son m\u00e1s resistentes, pero, en nuestro caso, trataremos con maderas blandas que poseen\u00a0 calidad suficiente para su uso en interiores: <strong>pino, cedro del L\u00edbano, casta\u00f1o, \u00e1lamo, abeto, abedul<\/strong>.<\/p>\n<p>Seg\u00fan como la vayamos a colocar, escogeremos una madera u otra. Si los paneles van a ir sobre la pared, una buena opci\u00f3n puede ser la madera de <strong>Paulownia<\/strong>\u00a0que adem\u00e1s de no tener nudos, es muy\u00a0<strong>ligera y \u00a0f\u00e1cil<\/strong>\u00a0de trabajar.<\/p>\n<h2><strong>Madera en listones<\/strong><\/h2>\n<p>Una tendencia muy en auge es el empleo de la madera en listones. La madera que se suele usar para este m\u00e9todo decorativo es de<strong>\u00a0haya<\/strong>, abeto o samba, aunque tambi\u00e9n podemos encontrarlo de madera de <strong>pino<\/strong>\u00a0en su variante m\u00e1s econ\u00f3mica. Si queremos una tonalidad clara y con pocos nudos, la madera ideal ser\u00eda\u00a0<strong>abeto o samba<\/strong>. Por otro lado, si buscamos una tonalidad m\u00e1s oscura, o en tonos rojizos y de gran durabilidad, optar\u00edamos por la madera de <strong>haya.<\/strong>\u00a0Podemos revestir la pared de un dormitorio en la zona del cabecero, utilizar listones como\u00a0separadores de estancias, utilizarlo en pasos de pasillos, zonas de ba\u00f1o, etc.<\/p>\n<blockquote class=\"left\">\n<h2><cite>&#8220;Todo es dise\u00f1o, y la calidad del dise\u00f1o afecta la calidad de nuestras vidas&#8221;. &#8211; <strong>Norman Foster.<\/strong><\/cite><\/h2>\n<\/blockquote>\n<h2><strong>Paneles<\/strong><strong>\u00a0OSB<\/strong><\/h2>\n<p>Los paneles OSB (<strong>oriented strand board<\/strong>) o tableros de fibras orientadas son tableros formados por sucesivas capas de\u00a0<strong>virutas prensadas<\/strong>\u00a0generalmente de madera de pino y abeto, donde se van uniendo las capas de forma perpendicular para conseguir una mayor estabilidad y resistencia, lo que los convierte en muchos \u00e1mbitos en una alternativa a la madera maciza.\u00a0 Suelen tener un grosor de entre 10 \u2013 28mm y su aspecto natural y sostenible lo hacen muy vers\u00e1til para la decoraci\u00f3n de espacios y mobiliario de estilo eco.<\/p>\n<h2><strong>Imitaci\u00f3n madera<\/strong><\/h2>\n<p>Tal es la pasi\u00f3n por la madera que no podemos acabar este art\u00edculo sin hacer menci\u00f3n a los materiales que la imitan, como es el caso del gres <strong>porcel\u00e1nico<\/strong>. Este material tan vers\u00e1til y duradero hace posible que nos llevemos la esencia de la madera a zonas de alta humedad como puede ser los ba\u00f1os y aseos o para segundas residencias en zonas rurales donde necesitemos suelos m\u00e1s sufridos y duraderos. El parecido visual con la madera natural es casi id\u00e9ntico y es cada vez \u00a0m\u00e1s com\u00fan verlo en todo tipo de estancias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este material lleva tiempo siendo tendencia en todas sus variantes y formas, y cada vez somos m\u00e1s los que apostamos por este tipo de materiales que nos producen sensaci\u00f3n de calidez, confianza y autenticidad. La madera se usa principalmente para revestir nuestros suelos, pero hoy venimos a contaros soluciones verticales, no solo existe la pintura, el alicatado o los papeles pintados para decorar nuestras paredes, tambi\u00e9n podemos recurrir a los\u00a0revestimientos de madera&#8230;<\/p>\n","protected":false},"author":1,"featured_media":463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/posts\/78"}],"collection":[{"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":5,"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/posts\/78\/revisions"}],"predecessor-version":[{"id":1846,"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/posts\/78\/revisions\/1846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/media\/463"}],"wp:attachment":[{"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/media?parent=78"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/categories?post=78"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iacodvzla.com\/index.php\/wp-json\/wp\/v2\/tags?post=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}